{"id":4419,"date":"2025-11-23T19:21:00","date_gmt":"2025-11-23T19:21:00","guid":{"rendered":"https:\/\/comprodiverso.com\/?p=4419"},"modified":"2025-11-27T16:01:12","modified_gmt":"2025-11-27T16:01:12","slug":"defis-en-matiere-demploi-personnes-handicapees-donnees-mexicaines","status":"publish","type":"post","link":"https:\/\/comprodiverso.com\/fr\/efemerides\/retos-laborales-personas-con-discapacidad-mexico-datos\/","title":{"rendered":"D\u00e9fis en mati\u00e8re d'emploi rencontr\u00e9s par les personnes handicap\u00e9es au Mexique"},"content":{"rendered":"<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Le 3 d\u00e9cembre marque la Journ\u00e9e internationale des personnes handicap\u00e9es. Nous allons donc explorer les d\u00e9fis auxquels ce secteur de la population est confront\u00e9 dans l'environnement de travail mexicain.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Journ\u00e9e internationale des personnes handicap\u00e9es, d\u00e9clar\u00e9e en 1992 par l'Assembl\u00e9e g\u00e9n\u00e9rale des Nations unies, est c\u00e9l\u00e9br\u00e9e le 3 d\u00e9cembre. <\/strong>Il est destin\u00e9 \u00e0 <strong>promouvoir les droits et le bien-\u00eatre des personnes handicap\u00e9es<\/strong>, ainsi qu'\u00e0 sensibiliser les citoyens \u00e0 l'importance de l'action de l'Union europ\u00e9enne dans le domaine de la sant\u00e9. <strong>les d\u00e9fis qui subsistent en mati\u00e8re d'inclusion<\/strong> dans les environnements sociaux et professionnels.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur la base des donn\u00e9es de l'Organisation mondiale de la sant\u00e9 (OMS), il a \u00e9t\u00e9 estim\u00e9 que <strong>d'ici 2023, il y aura environ 1,3 milliard de personnes souffrant d'un type de handicap au niveau international.<\/strong>. Ce chiffre repr\u00e9sente une valeur approximative de <strong>16% de la population mondiale<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 cet \u00e9gard, l'OMS note que <strong>les in\u00e9galit\u00e9s auxquelles sont confront\u00e9es les personnes handicap\u00e9es d\u00e9coulent d'un certain nombre de situations injustes auxquelles les personnes handicap\u00e9es sont souvent expos\u00e9es<\/strong>:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abLes in\u00e9galit\u00e9s en mati\u00e8re de sant\u00e9 d\u00e9coulent des situations injustes auxquelles sont confront\u00e9es les personnes handicap\u00e9es, telles que la stigmatisation, la discrimination, la pauvret\u00e9, l'exclusion de l'\u00e9ducation et de l'emploi, ainsi que des obstacles qu'elles rencontrent dans le syst\u00e8me de sant\u00e9 lui-m\u00eame.<\/p>\n<\/blockquote>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Chiffres cl\u00e9s sur les personnes handicap\u00e9es au Mexique<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Bas\u00e9 sur les donn\u00e9es de l'Institut national de la statistique et de la g\u00e9ographie (Inegi) dans le recensement de la population et du logement de 2020, <strong>Le Mexique comptait 6 179 890 personnes handicap\u00e9es<\/strong>, qui repr\u00e9sentait une <strong>4,9% de la population totale<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inegi souligne que la <strong>les personnes handicap\u00e9es ont eu des difficult\u00e9s \u00e0 effectuer certaines activit\u00e9s quotidiennes sp\u00e9cifiques<\/strong>par exemple :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>marcher, monter ou descendre<\/strong> (47.6%);<\/li>\n\n\n\n<li><strong>voir<\/strong>, m\u00eame avec des lunettes (43.5%) ;<\/li>\n\n\n\n<li><strong>entendre<\/strong>, m\u00eame si vous portez un appareil auditif (21.9%) ;<\/li>\n\n\n\n<li><strong>se laver, s'habiller ou manger <\/strong>(18.9%).<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, les \u00c9tats de&nbsp;<strong>Oaxaca<\/strong> (6.6%), <strong>Guerrero<\/strong> (6%) et <strong>Tabasco<\/strong> (6%)<strong> pr\u00e9sentait la plus forte concentration en pourcentage d'habitants vivant avec un handicap<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D'autre part, l'Organisation des Nations unies (ONU) souligne que les <strong>les personnes handicap\u00e9es sont plus susceptibles d'\u00eatre victimes de violences<\/strong>:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abLes enfants handicap\u00e9s sont 4 fois plus susceptibles d'\u00eatre victimes de violence, les adultes handicap\u00e9s sont 1,5 fois plus susceptibles d'\u00eatre victimes de violence\u00bb.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Au Mexique, les personnes appartenant \u00e0 ce secteur de la population <strong>sont plus fr\u00e9quemment expos\u00e9s \u00e0 la discrimination<\/strong>. Selon l'enqu\u00eate nationale sur la discrimination (Enadis) de 2022, des <strong>nombre total de personnes ayant v\u00e9cu un \u00e9pisode de discrimination, 33,8% \u00e9taient des personnes handicap\u00e9es.<\/strong>.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">D\u00e9fis rencontr\u00e9s par les personnes handicap\u00e9es sur le lieu de travail au Mexique<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Selon le recensement de la population et du logement de 2020 (Inegi),&nbsp;<strong>seulement 38% des personnes de plus de 15 ans souffrant d'un handicap \u00e9taient \u00e9conomiquement actives.<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, le probl\u00e8me de l'\u00e9cart salarial est toujours d'actualit\u00e9 au Mexique. <strong>L'Inegi lui-m\u00eame a indiqu\u00e9 qu'en 2022, le salaire mensuel d'une personne non handicap\u00e9e \u00e9tait de $8 373 pesos, tandis que celui d'une personne handicap\u00e9e \u00e9tait de $5 5 531 pesos.<\/strong>. Bien que le salaire minimum au Mexique en 2025 soit de $8 364 pesos par mois, il n'existe toujours pas de donn\u00e9es actualis\u00e9es sur la r\u00e9duction ou l'\u00e9largissement de l'\u00e9cart entre les personnes handicap\u00e9es et non handicap\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D'autre part, selon le rapport Enadis 2022, <strong>44,9% des personnes handicap\u00e9es interrog\u00e9es ont d\u00e9clar\u00e9 avoir \u00e9t\u00e9 victimes de discrimination lors de leur recherche d'emploi.<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, sur la base des recensements \u00e9conomiques de 2024 de l'Inegi, au Mexique <strong>il existe 5 468 180 unit\u00e9s \u00e9conomiques dans le secteur priv\u00e9 et dans les entreprises parapubliques, dont 102 285 seulement emploient des personnes handicap\u00e9es<\/strong>. Cela ne repr\u00e9sente que la<strong> 1,8% du nombre total d'unit\u00e9s \u00e9conomiques<\/strong>, L'inclusion de cette partie de la population dans le march\u00e9 du travail est encore loin d'\u00eatre acquise.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">De quelle mani\u00e8re pensez-vous pouvoir contribuer \u00e0 rendre l'environnement de travail plus inclusif pour les personnes handicap\u00e9es ?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Avec des informations provenant de <a href=\"https:\/\/www.gob.mx\/conadis\/articulos\/3-de-diciembre-dia-internacional-de-las-personas-con-discapacidad\" target=\"_blank\" rel=\"noreferrer noopener\">Gouvernement du Mexique<\/a>Inegi (<a href=\"https:\/\/www.inegi.org.mx\/contenidos\/saladeprensa\/aproposito\/2021\/EAP_PersDiscap21.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">1<\/a>, <a href=\"https:\/\/cuentame.inegi.org.mx\/explora\/poblacion\/discapacidad\/\" target=\"_blank\" rel=\"noreferrer noopener\">2<\/a>, <a href=\"https:\/\/www.inegi.org.mx\/contenidos\/programas\/enadis\/2022\/doc\/enadis2022_resultados.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">3<\/a> y <a href=\"https:\/\/www.inegi.org.mx\/contenidos\/programas\/ce\/2024\/doc\/ce2024_presenta.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">4<\/a>), LES NATIONS UNIES (<a href=\"https:\/\/www.un.org\/es\/observances\/day-of-persons-with-disabilities\" target=\"_blank\" rel=\"noreferrer noopener\">1<\/a> y <a href=\"https:\/\/www.un.org\/es\/observances\/day-of-persons-with-disabilities\/background\" target=\"_blank\" rel=\"noreferrer noopener\">2<\/a>) y <a href=\"https:\/\/www.who.int\/es\/news-room\/fact-sheets\/detail\/disability-and-health\" target=\"_blank\" rel=\"noreferrer noopener\">OMS (ORGANISATION MONDIALE DE LA SANT\u00c9)<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recherches et r\u00e9daction par Jos\u00e9 Manuel R\u00edos et Rodrigo Hern\u00e1ndez<\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez des faits sur ce que vivent les personnes handicap\u00e9es dans leur environnement de travail au Mexique.<\/p>","protected":false},"author":5,"featured_media":4459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80],"tags":[70,71,72,73],"class_list":["post-4419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-efemerides","tag-diversidad","tag-equidad","tag-inclusion","tag-inclusion-laboral"],"_links":{"self":[{"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/posts\/4419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/comments?post=4419"}],"version-history":[{"count":5,"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/posts\/4419\/revisions"}],"predecessor-version":[{"id":4589,"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/posts\/4419\/revisions\/4589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/media\/4459"}],"wp:attachment":[{"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/media?parent=4419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/categories?post=4419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comprodiverso.com\/fr\/wp-json\/wp\/v2\/tags?post=4419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}